{"id":2598,"date":"2017-10-18T20:07:22","date_gmt":"2017-10-18T20:07:22","guid":{"rendered":"https:\/\/laorotava.salesianos.edu\/colegio\/?page_id=2598"},"modified":"2026-02-27T13:10:56","modified_gmt":"2026-02-27T13:10:56","slug":"eso","status":"publish","type":"page","link":"https:\/\/laorotava.salesianos.edu\/colegio\/eso\/","title":{"rendered":"Secundaria"},"content":{"rendered":"<div id=\"fb-root\"><\/div>\n<p>[et_pb_section fb_built=\u00bb1&#8243; fullwidth=\u00bbon\u00bb _builder_version=\u00bb4.16&#8243; global_colors_info=\u00bb{}\u00bb][et_pb_fullwidth_header title=\u00bbSecundaria\u00bb module_class=\u00bbpagina-imagen-cabecera\u00bb _builder_version=\u00bb4.27.4&#8243; title_level=\u00bbh2&#8243; title_font=\u00bbGabriela|700|||||||\u00bb title_text_align=\u00bbright\u00bb title_text_color=\u00bb#ffffff\u00bb title_font_size=\u00bb80px\u00bb background_color=\u00bbrgba(255, 255, 255, 0)\u00bb background_image=\u00bbhttps:\/\/laorotava.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2025\/12\/WhatsApp-Image-2025-12-01-at-10.02.49-scaled.jpeg\u00bb max_width_tablet=\u00bb50px\u00bb title_text_shadow_style=\u00bbpreset5&#8243; global_colors_info=\u00bb{}\u00bb button_one_text_size__hover_enabled=\u00bboff\u00bb button_two_text_size__hover_enabled=\u00bboff\u00bb button_one_text_color__hover_enabled=\u00bboff\u00bb button_two_text_color__hover_enabled=\u00bboff\u00bb button_one_border_width__hover_enabled=\u00bboff\u00bb button_two_border_width__hover_enabled=\u00bboff\u00bb button_one_border_color__hover_enabled=\u00bboff\u00bb button_two_border_color__hover_enabled=\u00bboff\u00bb button_one_border_radius__hover_enabled=\u00bboff\u00bb button_two_border_radius__hover_enabled=\u00bboff\u00bb button_one_letter_spacing__hover_enabled=\u00bboff\u00bb button_two_letter_spacing__hover_enabled=\u00bboff\u00bb button_one_bg_color__hover_enabled=\u00bboff\u00bb button_two_bg_color__hover_enabled=\u00bboff\u00bb][\/et_pb_fullwidth_header][\/et_pb_section][et_pb_section fb_built=\u00bb1&#8243; module_class=\u00bbpagina-seccion-contenido\u00bb _builder_version=\u00bb4.16&#8243; custom_padding=\u00bb0%|||\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_row column_structure=\u00bb2_3,1_3&#8243; module_class=\u00bbpagina-texto\u00bb _builder_version=\u00bb4.16&#8243; background_size=\u00bbinitial\u00bb background_position=\u00bbtop_left\u00bb background_repeat=\u00bbrepeat\u00bb custom_margin=\u00bb25px|||\u00bb custom_padding=\u00bb25px||0px|\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb2_3&#8243; _builder_version=\u00bb4.16&#8243; custom_padding=\u00bb|||\u00bb global_colors_info=\u00bb{}\u00bb custom_padding__hover=\u00bb|||\u00bb][et_pb_text admin_label=\u00bbTexto\u00bb _builder_version=\u00bb4.16&#8243; background_size=\u00bbinitial\u00bb background_position=\u00bbtop_left\u00bb background_repeat=\u00bbrepeat\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<h1>Educaci\u00f3n Secundaria Obligatoria<\/h1>\n<p>[\/et_pb_text][et_pb_text _builder_version=\u00bb4.23.4&#8243; custom_padding=\u00bb||0px|||\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<div>\n<div>\n<p>La <strong>Educaci\u00f3n Secundaria Obligatoria<\/strong> es una etapa educativa obligatoria que abarca <strong>desde los 12 hasta los 16 a\u00f1os.<\/strong><\/p>\n<p>Se compone de cuatro cursos en los que el alumnado recibir\u00e1 una formaci\u00f3n integral desarrollando capacidades y adquiriendo conocimientos que le ser\u00e1n imprescindibles para su futuro acad\u00e9mico.<\/p>\n<p>Al final de la etapa, el alumnado estar\u00e1 en disposici\u00f3n de obtener el <strong>t\u00edtulo de Educaci\u00f3n Secundaria<\/strong>, que le permitir\u00e1 acceder a <strong>estudios pre-universitarios<\/strong> (Bachillerato) o a <strong>estudios profesionales<\/strong> (Grados Formaci\u00f3n Profesional).<\/p>\n<\/div>\n<\/div>\n<p>[\/et_pb_text][et_pb_text _builder_version=\u00bb4.16&#8243; global_colors_info=\u00bb{}\u00bb]<\/p>\n<h2>\u00bfC\u00f3mo ayudamos a nuestro alumnado a conseguirlo?<\/h2>\n<p style=\"text-align: justify;\">T<span style=\"font-weight: 400;\">odo el claustro de la etapa est\u00e1 volcado en acompa\u00f1ar al alumnado en su d\u00eda a d\u00eda. Para nosotros, son <\/span><b>el centro de nuestra labor educativa<\/b><span style=\"font-weight: 400;\">, tratando de desarrollar las cualidades del modelo de persona en cada uno de ellos al culminar su paso por nuestro Centro.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">Nuestra excelencia acad\u00e9mica, sin duda, ir\u00e1 de la mano de una <\/span><b>convivencia sana y de respeto<\/b><span style=\"font-weight: 400;\">. Un buen clima de trabajo y de relaciones en el aula generar\u00e1 personas felices y motivadas. Por eso, cobran especial importancia el cuidado y desarrollo de acciones que garanticen un trabajo serio y continuado en ese sentido, acciones que se vertebran y se coordinan desde el Plan de Acci\u00f3n Tutorial, pasando por los diversos planes de centro como el Plan de Igualdad y el Plan de Convivencia positiva, hasta la acci\u00f3n directa de nuestro equipo de tutores y la Comisi\u00f3n de Bienestar y Convivencia, que con sus acciones de prevenci\u00f3n y formaci\u00f3n, ayudan al acompa\u00f1amiento del alumnado para garantizar ese ambiente de convivencia pac\u00edfica y acogida familiar que se percibe en el Centro<\/span><span style=\"font-size: 14px;\">:<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Por otro lado, para que nuestros alumnos y alumnas alcancen sus objetivos formativos:<\/span><\/p>\n<ul>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><b>Utilizamos metodolog\u00edas activas:<\/b><span style=\"font-weight: 400;\"> como el aprendizaje cooperativo, el aprendizaje-servicio, aprendizaje por proyectos, etc. Todas estas metodolog\u00edas activas tienen como centro el propio alumnado, que se convierte en protagonista de los procesos de ense\u00f1anza aprendizaje\u00a0 a trav\u00e9s de su interacci\u00f3n con sus iguales y con el entorno.\u00a0<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Sin perder de vista la integraci\u00f3n en etapas de educaci\u00f3n superior, tratamos de preparar al alumnado en una <\/span><b>cultura del esfuerzo y la planificaci\u00f3n<\/b><span style=\"font-weight: 400;\">, ofreci\u00e9ndole una <\/span><b>orientaci\u00f3n vocacional y profesional muy individualizada<\/b><span style=\"font-weight: 400;\">, centrada en el desarrollo de su potencial y capacidades, pero favoreciendo adem\u00e1s su pensamiento cr\u00edtico y reflexi\u00f3n personal.\u00a0<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Proyecto 1 to 1, en el que el <\/span><b>uso de las nuevas tecnolog\u00edas <\/b><span style=\"font-weight: 400;\">se focaliza en el acceso a la informaci\u00f3n desde el pensamiento reflexivo y cr\u00edtico, trabajando la b\u00fasqueda, selecci\u00f3n y uso de la misma para la generaci\u00f3n de nuevos conocimientos, con una actitud responsable y respetuosa en todos los sentidos.\u00a0<\/span><\/li>\n<\/ul>\n<ul>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><b>Inmersi\u00f3n ling\u00fc\u00edstica<\/b><span style=\"font-weight: 400;\"> que se articula con la dotaci\u00f3n de un n\u00famero mayor de horas de ense\u00f1anza con el ingl\u00e9s como lengua vehicular, a lo que se suma la presencia de un auxiliar de conversaci\u00f3n para todos los cursos de la etapa.\u00a0 A estas medidas ordinarias hay que a\u00f1adir toda una serie de acciones extraordinarias planificadas desde los diversos cursos para garantizar esa inmersi\u00f3n. Destaca especialmente nuestro viaje de inmersi\u00f3n ling\u00fc\u00edstica ofertado en alg\u00fan curso de la etapa, as\u00ed como la posibilidad de cursar el <\/span><b>American High School Diploma para la obtenci\u00f3n del Diploma Dual<\/b><span style=\"font-weight: 400;\">.<\/span><\/li>\n<\/ul>\n<p style=\"text-align: justify;\"><b>Promovemos actividades <\/b><span style=\"font-weight: 400;\">que van de lo acad\u00e9mico a <\/span><b>lo personal y humano, <\/b><span style=\"font-weight: 400;\">enriqueciendo la ense\u00f1anza en el aula con actividades complementarias que ayudan a contextualizar el aprendizaje en la realidad. Y permiten el desarrollo de los valores inherentes al ser humano, en plena consonancia con nuestro modelo de persona. Las convivencias, campa\u00f1as solidarias y de voluntariado ayudan a nuestro alumnado a\u00a0 aprender, desde la experiencia, lo que es estar al servicio de los dem\u00e1s; potenciando en ellos competencias que los ayudar\u00e1n a formar parte de un mundo m\u00e1s solidario y respetuoso.<\/span><\/p>\n<ul><\/ul>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=\u00bb1_3&#8243; _builder_version=\u00bb4.16&#8243; custom_padding=\u00bb|||\u00bb global_colors_info=\u00bb{}\u00bb custom_padding__hover=\u00bb|||\u00bb][et_pb_text _builder_version=\u00bb4.16&#8243; text_font=\u00bbLato Light||||\u00bb text_text_color=\u00bb#e02b20&#8243; text_font_size=\u00bb28px\u00bb custom_margin=\u00bb||35px|\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p>Te ofrecemos&#8230;<\/p>\n<p>[\/et_pb_text][et_pb_button button_url=\u00bbhttps:\/\/laorotava.salesianos.edu\/colegio\/comedor-escolar\/\u00bb button_text=\u00bbServicio de comedor\u00bb _builder_version=\u00bb4.16&#8243; custom_button=\u00bbon\u00bb button_text_color=\u00bb#ffffff\u00bb button_bg_color=\u00bb#e02b20&#8243; button_border_width=\u00bb0px\u00bb button_border_radius=\u00bb6px\u00bb box_shadow_style=\u00bbpreset2&#8243; global_colors_info=\u00bb{}\u00bb button_text_size__hover_enabled=\u00bboff\u00bb button_one_text_size__hover_enabled=\u00bboff\u00bb button_two_text_size__hover_enabled=\u00bboff\u00bb button_text_color__hover_enabled=\u00bboff\u00bb button_one_text_color__hover_enabled=\u00bboff\u00bb button_two_text_color__hover_enabled=\u00bboff\u00bb button_border_width__hover_enabled=\u00bboff\u00bb button_one_border_width__hover_enabled=\u00bboff\u00bb button_two_border_width__hover_enabled=\u00bboff\u00bb button_border_color__hover_enabled=\u00bboff\u00bb button_one_border_color__hover_enabled=\u00bboff\u00bb button_two_border_color__hover_enabled=\u00bboff\u00bb button_border_radius__hover_enabled=\u00bboff\u00bb button_one_border_radius__hover_enabled=\u00bboff\u00bb button_two_border_radius__hover_enabled=\u00bboff\u00bb button_letter_spacing__hover_enabled=\u00bboff\u00bb button_one_letter_spacing__hover_enabled=\u00bboff\u00bb button_two_letter_spacing__hover_enabled=\u00bboff\u00bb button_bg_color__hover_enabled=\u00bboff\u00bb button_one_bg_color__hover_enabled=\u00bboff\u00bb button_two_bg_color__hover_enabled=\u00bboff\u00bb]&nbsp;<br \/>\n[\/et_pb_button][et_pb_button button_url=\u00bbhttps:\/\/laorotava.salesianos.edu\/colegio\/actividades-extraescolares\/\u00bb url_new_window=\u00bbon\u00bb button_text=\u00bbActividades extraescolares\u00bb _builder_version=\u00bb4.16&#8243; custom_button=\u00bbon\u00bb button_text_color=\u00bb#ffffff\u00bb button_bg_color=\u00bb#e02b20&#8243; button_border_width=\u00bb0px\u00bb button_border_radius=\u00bb6px\u00bb button_font=\u00bb||||\u00bb box_shadow_style=\u00bbpreset2&#8243; global_colors_info=\u00bb{}\u00bb button_text_size__hover_enabled=\u00bboff\u00bb button_one_text_size__hover_enabled=\u00bboff\u00bb button_two_text_size__hover_enabled=\u00bboff\u00bb button_text_color__hover_enabled=\u00bboff\u00bb button_one_text_color__hover_enabled=\u00bboff\u00bb button_two_text_color__hover_enabled=\u00bboff\u00bb button_border_width__hover_enabled=\u00bboff\u00bb button_one_border_width__hover_enabled=\u00bboff\u00bb button_two_border_width__hover_enabled=\u00bboff\u00bb button_border_color__hover_enabled=\u00bboff\u00bb button_one_border_color__hover_enabled=\u00bboff\u00bb button_two_border_color__hover_enabled=\u00bboff\u00bb button_border_radius__hover_enabled=\u00bboff\u00bb button_one_border_radius__hover_enabled=\u00bboff\u00bb button_two_border_radius__hover_enabled=\u00bboff\u00bb button_letter_spacing__hover_enabled=\u00bboff\u00bb button_one_letter_spacing__hover_enabled=\u00bboff\u00bb button_two_letter_spacing__hover_enabled=\u00bboff\u00bb button_bg_color__hover_enabled=\u00bboff\u00bb button_one_bg_color__hover_enabled=\u00bboff\u00bb button_two_bg_color__hover_enabled=\u00bboff\u00bb]&nbsp;<br \/>\n[\/et_pb_button][et_pb_button button_url=\u00bbhttp:\/\/qualitasescuelafamilia.com\u00bb url_new_window=\u00bbon\u00bb button_text=\u00bbPlataforma Qe\u00bb _builder_version=\u00bb4.16&#8243; custom_button=\u00bbon\u00bb button_text_color=\u00bb#ffffff\u00bb button_bg_color=\u00bb#e02b20&#8243; button_border_width=\u00bb0px\u00bb button_border_radius=\u00bb6px\u00bb button_font=\u00bb||||\u00bb box_shadow_style=\u00bbpreset2&#8243; global_colors_info=\u00bb{}\u00bb button_text_size__hover_enabled=\u00bboff\u00bb button_one_text_size__hover_enabled=\u00bboff\u00bb button_two_text_size__hover_enabled=\u00bboff\u00bb button_text_color__hover_enabled=\u00bboff\u00bb button_one_text_color__hover_enabled=\u00bboff\u00bb button_two_text_color__hover_enabled=\u00bboff\u00bb button_border_width__hover_enabled=\u00bboff\u00bb button_one_border_width__hover_enabled=\u00bboff\u00bb button_two_border_width__hover_enabled=\u00bboff\u00bb button_border_color__hover_enabled=\u00bboff\u00bb button_one_border_color__hover_enabled=\u00bboff\u00bb button_two_border_color__hover_enabled=\u00bboff\u00bb button_border_radius__hover_enabled=\u00bboff\u00bb button_one_border_radius__hover_enabled=\u00bboff\u00bb button_two_border_radius__hover_enabled=\u00bboff\u00bb button_letter_spacing__hover_enabled=\u00bboff\u00bb button_one_letter_spacing__hover_enabled=\u00bboff\u00bb button_two_letter_spacing__hover_enabled=\u00bboff\u00bb button_bg_color__hover_enabled=\u00bboff\u00bb button_one_bg_color__hover_enabled=\u00bboff\u00bb button_two_bg_color__hover_enabled=\u00bboff\u00bb]&nbsp;<br \/>\n[\/et_pb_button][et_pb_button button_url=\u00bbhttps:\/\/laorotava.salesianos.edu\/colegio\/proyectos-pedagogicos\/\u00bb button_text=\u00bbProyectos Pedag\u00f3gicos\u00bb _builder_version=\u00bb4.16&#8243; custom_button=\u00bbon\u00bb button_text_color=\u00bb#ffffff\u00bb button_bg_color=\u00bb#e02b20&#8243; button_border_width=\u00bb0px\u00bb button_border_radius=\u00bb6px\u00bb box_shadow_style=\u00bbpreset2&#8243; global_colors_info=\u00bb{}\u00bb button_text_size__hover_enabled=\u00bboff\u00bb button_one_text_size__hover_enabled=\u00bboff\u00bb button_two_text_size__hover_enabled=\u00bboff\u00bb button_text_color__hover_enabled=\u00bboff\u00bb button_one_text_color__hover_enabled=\u00bboff\u00bb button_two_text_color__hover_enabled=\u00bboff\u00bb button_border_width__hover_enabled=\u00bboff\u00bb button_one_border_width__hover_enabled=\u00bboff\u00bb button_two_border_width__hover_enabled=\u00bboff\u00bb button_border_color__hover_enabled=\u00bboff\u00bb button_one_border_color__hover_enabled=\u00bboff\u00bb button_two_border_color__hover_enabled=\u00bboff\u00bb button_border_radius__hover_enabled=\u00bboff\u00bb button_one_border_radius__hover_enabled=\u00bboff\u00bb button_two_border_radius__hover_enabled=\u00bboff\u00bb button_letter_spacing__hover_enabled=\u00bboff\u00bb button_one_letter_spacing__hover_enabled=\u00bboff\u00bb button_two_letter_spacing__hover_enabled=\u00bboff\u00bb button_bg_color__hover_enabled=\u00bboff\u00bb button_one_bg_color__hover_enabled=\u00bboff\u00bb button_two_bg_color__hover_enabled=\u00bboff\u00bb]&nbsp;<br \/>\n[\/et_pb_button][et_pb_button button_url=\u00bbhttps:\/\/laorotava.salesianos.edu\/deporte\/\u00bb button_text=\u00bbActividades deportivas\u00bb _builder_version=\u00bb4.16&#8243; custom_button=\u00bbon\u00bb button_text_color=\u00bb#ffffff\u00bb button_bg_color=\u00bb#e02b20&#8243; button_border_width=\u00bb0px\u00bb button_border_radius=\u00bb6px\u00bb box_shadow_style=\u00bbpreset2&#8243; global_colors_info=\u00bb{}\u00bb button_text_size__hover_enabled=\u00bboff\u00bb button_one_text_size__hover_enabled=\u00bboff\u00bb button_two_text_size__hover_enabled=\u00bboff\u00bb button_text_color__hover_enabled=\u00bboff\u00bb button_one_text_color__hover_enabled=\u00bboff\u00bb button_two_text_color__hover_enabled=\u00bboff\u00bb button_border_width__hover_enabled=\u00bboff\u00bb button_one_border_width__hover_enabled=\u00bboff\u00bb button_two_border_width__hover_enabled=\u00bboff\u00bb button_border_color__hover_enabled=\u00bboff\u00bb button_one_border_color__hover_enabled=\u00bboff\u00bb button_two_border_color__hover_enabled=\u00bboff\u00bb button_border_radius__hover_enabled=\u00bboff\u00bb button_one_border_radius__hover_enabled=\u00bboff\u00bb button_two_border_radius__hover_enabled=\u00bboff\u00bb button_letter_spacing__hover_enabled=\u00bboff\u00bb button_one_letter_spacing__hover_enabled=\u00bboff\u00bb button_two_letter_spacing__hover_enabled=\u00bboff\u00bb button_bg_color__hover_enabled=\u00bboff\u00bb button_one_bg_color__hover_enabled=\u00bboff\u00bb button_two_bg_color__hover_enabled=\u00bboff\u00bb]&nbsp;<br \/>\n[\/et_pb_button][et_pb_button button_url=\u00bbhttps:\/\/laorotava.salesianos.edu\/colegio\/eso\/\u00bb button_text=\u00bbEnfermera Escolar\u00bb disabled_on=\u00bbon|on|on\u00bb _builder_version=\u00bb4.16&#8243; custom_button=\u00bbon\u00bb button_text_color=\u00bb#ffffff\u00bb button_bg_color=\u00bb#e02b20&#8243; button_border_width=\u00bb0px\u00bb button_border_radius=\u00bb6px\u00bb box_shadow_style=\u00bbpreset2&#8243; disabled=\u00bbon\u00bb global_colors_info=\u00bb{}\u00bb button_text_size__hover_enabled=\u00bboff\u00bb button_one_text_size__hover_enabled=\u00bboff\u00bb button_two_text_size__hover_enabled=\u00bboff\u00bb button_text_color__hover_enabled=\u00bboff\u00bb button_one_text_color__hover_enabled=\u00bboff\u00bb button_two_text_color__hover_enabled=\u00bboff\u00bb button_border_width__hover_enabled=\u00bboff\u00bb button_one_border_width__hover_enabled=\u00bboff\u00bb button_two_border_width__hover_enabled=\u00bboff\u00bb button_border_color__hover_enabled=\u00bboff\u00bb button_one_border_color__hover_enabled=\u00bboff\u00bb button_two_border_color__hover_enabled=\u00bboff\u00bb button_border_radius__hover_enabled=\u00bboff\u00bb button_one_border_radius__hover_enabled=\u00bboff\u00bb button_two_border_radius__hover_enabled=\u00bboff\u00bb button_letter_spacing__hover_enabled=\u00bboff\u00bb button_one_letter_spacing__hover_enabled=\u00bboff\u00bb button_two_letter_spacing__hover_enabled=\u00bboff\u00bb button_bg_color__hover_enabled=\u00bboff\u00bb button_one_bg_color__hover_enabled=\u00bboff\u00bb button_two_bg_color__hover_enabled=\u00bboff\u00bb]&nbsp;<br \/>\n[\/et_pb_button][et_pb_button button_url=\u00bbhttps:\/\/laorotava.salesianos.edu\/colegio\/biblioteca\/\u00bb button_text=\u00bbBiblioteca\u00bb disabled_on=\u00bbon|on|on\u00bb _builder_version=\u00bb4.16&#8243; custom_button=\u00bbon\u00bb button_text_color=\u00bb#ffffff\u00bb button_bg_color=\u00bb#e02b20&#8243; button_border_width=\u00bb0px\u00bb button_border_radius=\u00bb6px\u00bb box_shadow_style=\u00bbpreset2&#8243; disabled=\u00bbon\u00bb global_colors_info=\u00bb{}\u00bb button_text_size__hover_enabled=\u00bboff\u00bb button_one_text_size__hover_enabled=\u00bboff\u00bb button_two_text_size__hover_enabled=\u00bboff\u00bb button_text_color__hover_enabled=\u00bboff\u00bb button_one_text_color__hover_enabled=\u00bboff\u00bb button_two_text_color__hover_enabled=\u00bboff\u00bb button_border_width__hover_enabled=\u00bboff\u00bb button_one_border_width__hover_enabled=\u00bboff\u00bb button_two_border_width__hover_enabled=\u00bboff\u00bb button_border_color__hover_enabled=\u00bboff\u00bb button_one_border_color__hover_enabled=\u00bboff\u00bb button_two_border_color__hover_enabled=\u00bboff\u00bb button_border_radius__hover_enabled=\u00bboff\u00bb button_one_border_radius__hover_enabled=\u00bboff\u00bb button_two_border_radius__hover_enabled=\u00bboff\u00bb button_letter_spacing__hover_enabled=\u00bboff\u00bb button_one_letter_spacing__hover_enabled=\u00bboff\u00bb button_two_letter_spacing__hover_enabled=\u00bboff\u00bb button_bg_color__hover_enabled=\u00bboff\u00bb button_one_bg_color__hover_enabled=\u00bboff\u00bb button_two_bg_color__hover_enabled=\u00bboff\u00bb]&nbsp;<br \/>\n[\/et_pb_button][et_pb_image src=\u00bbhttps:\/\/laorotava.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2023\/01\/Banner-BIRRETE_Diploma-Dual.jpg\u00bb title_text=\u00bbDiploma-Dual Salesianos La Orotava\u00bb _builder_version=\u00bb4.19.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_image][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00bb4.16&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb disabled_on=\u00bbon|on|on\u00bb disabled=\u00bbon\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.16&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_text _builder_version=\u00bb4.16&#8243; text_font=\u00bbLato Light||||\u00bb text_text_color=\u00bb#e02b20&#8243; text_font_size=\u00bb28px\u00bb custom_margin=\u00bb40px||20px|\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p>Echa un vistazo&#8230;<\/p>\n<p>[\/et_pb_text][et_pb_video src=\u00bbhttps:\/\/www.youtube.com\/watch?v=HkPiVcvT0_k&#038;t=3s\u00bb _builder_version=\u00bb4.16&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_video][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00bb4.16&#8243; global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.16&#8243; custom_padding=\u00bb|||\u00bb global_colors_info=\u00bb{}\u00bb custom_padding__hover=\u00bb|||\u00bb][et_pb_text _builder_version=\u00bb4.16&#8243; text_font=\u00bbLato Light||||\u00bb text_text_color=\u00bb#e02b20&#8243; text_font_size=\u00bb29px\u00bb custom_margin=\u00bb||25px|\u00bb hover_enabled=\u00bb0&#8243; global_colors_info=\u00bb{}\u00bb sticky_enabled=\u00bb0&#8243;]Para saber m\u00e1s sobre&#8230;<br \/>\n[\/et_pb_text][et_pb_tabs _builder_version=\u00bb4.16&#8243; global_colors_info=\u00bb{}\u00bb][et_pb_tab title=\u00bbDiversidad\u00bb _builder_version=\u00bb4.16&#8243; body_font=\u00bb||||\u00bb tab_font=\u00bb||||\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<h2 style=\"text-align: justify;\">\u00bfC\u00f3mo tratamos la diversidad?<\/h2>\n<p style=\"text-align: justify;\">Dando respuesta al alumnado con Necesidades Espec\u00edficas de Apoyo Educativo (NEAE) o carencias en el \u00e1mbito acad\u00e9mico-personal, a trav\u00e9s de diferentes actuaciones en coordinaci\u00f3n con el equipo educativo y el Departamento de Orientaci\u00f3n, inmersas en nuestro Plan Diversia.<\/p>\n<p>[\/et_pb_tab][et_pb_tab title=\u00bbPluriling\u00fcismo\u00bb _builder_version=\u00bb4.16&#8243; body_font=\u00bb||||\u00bb tab_font=\u00bb||||\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<h2 style=\"text-align: justify;\">\u00bfC\u00f3mo trabajamos el pluriling\u00fcismo?<\/h2>\n<p class=\"Estilopredeterminado\" style=\"text-align: justify;\">Aparte de la asignatura de ingl\u00e9s, el centro ha apostado por una inmersi\u00f3n ling\u00fc\u00edstica mayor ya que a lo largo de los cursos otras asignaturas se imparten en ingl\u00e9s. Adem\u00e1s, contamos con la presencia de una auxiliar de conversaci\u00f3n que ofrece una atenci\u00f3n m\u00e1s individualizada de la competencia oral.<\/p>\n<p>[\/et_pb_tab][et_pb_tab title=\u00bbOrganizaci\u00f3n\u00bb _builder_version=\u00bb4.16&#8243; body_font=\u00bb||||\u00bb tab_font=\u00bb||||\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<h2 style=\"text-align: justify;\">\u00bfQui\u00e9nes formamos el equipo de la ESO y c\u00f3mo nos organizamos?<\/h2>\n<p>Contamos con un jefe de estudios y dos coordinadores de ciclo que se encargan de organizar la etapa.<\/p>\n<p>Adem\u00e1s tenemos 12 tutores y m\u00e1s profesores que son los responsables de llevar a cabo la acci\u00f3n docente. En total somos 23 personas que trabajamos en el proyecto educativo pastoral de la etapa.<\/p>\n<p>[\/et_pb_tab][et_pb_tab title=\u00bbInstalaciones\u00bb _builder_version=\u00bb4.16&#8243; body_font=\u00bb||||\u00bb tab_font=\u00bb||||\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p>&nbsp;<\/p>\n<h2 style=\"text-align: justify;\">\u00bfCon qu\u00e9 instalaciones contamos?<\/h2>\n<p style=\"text-align: justify;\">El Colegio dispone de dos zonas de aulas y dos zonas de recreos y actividades deportivas.<\/p>\n<p>Tambi\u00e9n contamos con aula de fabricaci\u00f3n FABLAB, aula de Tecnolog\u00eda, aula de Educaci\u00f3n Pl\u00e1stica, aula y laboratorio de ciencias, sal\u00f3n de actos, capilla y zonas de trabajo administrativo.<\/p>\n<p>[\/et_pb_tab][\/et_pb_tabs][\/et_pb_column][\/et_pb_row][et_pb_row admin_label=\u00bbPREGUNTAS FRECUNTES\u00bb _builder_version=\u00bb4.16&#8243; custom_margin=\u00bb0px|||\u00bb custom_padding=\u00bb0px|0px|23.96875px|0px\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.16&#8243; custom_padding=\u00bb|||\u00bb global_colors_info=\u00bb{}\u00bb custom_padding__hover=\u00bb|||\u00bb][et_pb_text _builder_version=\u00bb4.16&#8243; text_font=\u00bb||||\u00bb text_font_size=\u00bb21px\u00bb header_font=\u00bb||||\u00bb header_font_size=\u00bb44px\u00bb background_color=\u00bb#e02b20&#8243; background_layout=\u00bbdark\u00bb custom_margin=\u00bb25px|||\u00bb custom_padding=\u00bb20px||10px|\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<h2>\u00a0 \u00a0 PREGUNTAS FRECUENTES<\/h2>\n<p>[\/et_pb_text][et_pb_accordion _builder_version=\u00bb4.16&#8243; toggle_text_color=\u00bb#dc001b\u00bb toggle_font_size=\u00bb17px\u00bb border_width_all=\u00bb0px\u00bb border_color_all=\u00bb#e5e5e5&#8243; use_border_color=\u00bbon\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_accordion_item title=\u00bb\u00bfQu\u00e9 horario tienen los alumnos de la ESO?\u00bb open=\u00bbon\u00bb _builder_version=\u00bb4.16&#8243; global_colors_info=\u00bb{}\u00bb]<\/p>\n<p>El horario de entrada de Secundaria es las 08.00 horas. Un primer timbre suena a las 7:55 horas y el segundo a las 8:00 horas, momento en el que comienzan las clases.<\/p>\n<p>La salida de los alumnos es a las 14:00 horas.<\/p>\n<p>[\/et_pb_accordion_item][et_pb_accordion_item title=\u00bb\u00bfC\u00f3mo es la comunicaci\u00f3n Escuela-Familia?\u00bb _builder_version=\u00bb4.16&#8243; global_colors_info=\u00bb{}\u00bb open=\u00bboff\u00bb]<\/p>\n<p>Consideramos que la comunicaci\u00f3n Escuela-Familia y Familia-Escuela es fundamental para todo el proceso de aprendizaje de los alumnos. Para ello utilizamos la app Qualitas Escuela Familia. A trav\u00e9s de ella, recibir\u00e1s toda la informaci\u00f3n de nuestro colegio y adem\u00e1s podr\u00e1s ponerte en contacto con los distintos profesores.<\/p>\n<p>[\/et_pb_accordion_item][\/et_pb_accordion][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Educaci\u00f3n Secundaria Obligatoria La Educaci\u00f3n Secundaria Obligatoria es una etapa educativa obligatoria que abarca desde los 12 hasta los 16 a\u00f1os. Se compone de cuatro cursos en los que el alumnado recibir\u00e1 una formaci\u00f3n integral desarrollando capacidades y adquiriendo conocimientos que le ser\u00e1n imprescindibles para su futuro acad\u00e9mico. Al final de la etapa, el alumnado [&hellip;]<\/p>\n<p><!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":3,"featured_media":2655,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"<p>ESO<\/p>","_et_gb_content_width":"","footnotes":""},"class_list":["post-2598","page","type-page","status-publish","has-post-thumbnail","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Secundaria - Colegio Salesiano San Isidro<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/laorotava.salesianos.edu\/colegio\/eso\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Secundaria - Colegio Salesiano San Isidro\" \/>\n<meta property=\"og:description\" content=\"Educaci\u00f3n Secundaria Obligatoria La Educaci\u00f3n Secundaria Obligatoria es una etapa educativa obligatoria que abarca desde los 12 hasta los 16 a\u00f1os. Se compone de cuatro cursos en los que el alumnado recibir\u00e1 una formaci\u00f3n integral desarrollando capacidades y adquiriendo conocimientos que le ser\u00e1n imprescindibles para su futuro acad\u00e9mico. Al final de la etapa, el alumnado [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/laorotava.salesianos.edu\/colegio\/eso\/\" \/>\n<meta property=\"og:site_name\" content=\"Colegio Salesiano San Isidro\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-27T13:10:56+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/laorotava.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2017\/05\/Cabecera.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1075\" \/>\n\t<meta property=\"og:image:height\" content=\"174\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/laorotava.salesianos.edu\\\/colegio\\\/eso\\\/\",\"url\":\"https:\\\/\\\/laorotava.salesianos.edu\\\/colegio\\\/eso\\\/\",\"name\":\"Secundaria - Colegio Salesiano San Isidro\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/laorotava.salesianos.edu\\\/colegio\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/laorotava.salesianos.edu\\\/colegio\\\/eso\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/laorotava.salesianos.edu\\\/colegio\\\/eso\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/laorotava.salesianos.edu\\\/colegio\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2017\\\/05\\\/Cabecera.png\",\"datePublished\":\"2017-10-18T20:07:22+00:00\",\"dateModified\":\"2026-02-27T13:10:56+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/laorotava.salesianos.edu\\\/colegio\\\/eso\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/laorotava.salesianos.edu\\\/colegio\\\/eso\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/laorotava.salesianos.edu\\\/colegio\\\/eso\\\/#primaryimage\",\"url\":\"https:\\\/\\\/laorotava.salesianos.edu\\\/colegio\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2017\\\/05\\\/Cabecera.png\",\"contentUrl\":\"https:\\\/\\\/laorotava.salesianos.edu\\\/colegio\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2017\\\/05\\\/Cabecera.png\",\"width\":1075,\"height\":174},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/laorotava.salesianos.edu\\\/colegio\\\/eso\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/laorotava.salesianos.edu\\\/colegio\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Secundaria\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/laorotava.salesianos.edu\\\/colegio\\\/#website\",\"url\":\"https:\\\/\\\/laorotava.salesianos.edu\\\/colegio\\\/\",\"name\":\"Colegio Salesiano San Isidro\",\"description\":\"P\u00e1gina oficial Colegio Salesiano San Isidro\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/laorotava.salesianos.edu\\\/colegio\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Secundaria - Colegio Salesiano San Isidro","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/laorotava.salesianos.edu\/colegio\/eso\/","og_locale":"es_ES","og_type":"article","og_title":"Secundaria - Colegio Salesiano San Isidro","og_description":"Educaci\u00f3n Secundaria Obligatoria La Educaci\u00f3n Secundaria Obligatoria es una etapa educativa obligatoria que abarca desde los 12 hasta los 16 a\u00f1os. Se compone de cuatro cursos en los que el alumnado recibir\u00e1 una formaci\u00f3n integral desarrollando capacidades y adquiriendo conocimientos que le ser\u00e1n imprescindibles para su futuro acad\u00e9mico. Al final de la etapa, el alumnado [&hellip;]","og_url":"https:\/\/laorotava.salesianos.edu\/colegio\/eso\/","og_site_name":"Colegio Salesiano San Isidro","article_modified_time":"2026-02-27T13:10:56+00:00","og_image":[{"width":1075,"height":174,"url":"https:\/\/laorotava.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2017\/05\/Cabecera.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/laorotava.salesianos.edu\/colegio\/eso\/","url":"https:\/\/laorotava.salesianos.edu\/colegio\/eso\/","name":"Secundaria - Colegio Salesiano San Isidro","isPartOf":{"@id":"https:\/\/laorotava.salesianos.edu\/colegio\/#website"},"primaryImageOfPage":{"@id":"https:\/\/laorotava.salesianos.edu\/colegio\/eso\/#primaryimage"},"image":{"@id":"https:\/\/laorotava.salesianos.edu\/colegio\/eso\/#primaryimage"},"thumbnailUrl":"https:\/\/laorotava.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2017\/05\/Cabecera.png","datePublished":"2017-10-18T20:07:22+00:00","dateModified":"2026-02-27T13:10:56+00:00","breadcrumb":{"@id":"https:\/\/laorotava.salesianos.edu\/colegio\/eso\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/laorotava.salesianos.edu\/colegio\/eso\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/laorotava.salesianos.edu\/colegio\/eso\/#primaryimage","url":"https:\/\/laorotava.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2017\/05\/Cabecera.png","contentUrl":"https:\/\/laorotava.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2017\/05\/Cabecera.png","width":1075,"height":174},{"@type":"BreadcrumbList","@id":"https:\/\/laorotava.salesianos.edu\/colegio\/eso\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/laorotava.salesianos.edu\/colegio\/"},{"@type":"ListItem","position":2,"name":"Secundaria"}]},{"@type":"WebSite","@id":"https:\/\/laorotava.salesianos.edu\/colegio\/#website","url":"https:\/\/laorotava.salesianos.edu\/colegio\/","name":"Colegio Salesiano San Isidro","description":"P\u00e1gina oficial Colegio Salesiano San Isidro","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/laorotava.salesianos.edu\/colegio\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"}]}},"_links":{"self":[{"href":"https:\/\/laorotava.salesianos.edu\/colegio\/wp-json\/wp\/v2\/pages\/2598","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/laorotava.salesianos.edu\/colegio\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/laorotava.salesianos.edu\/colegio\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/laorotava.salesianos.edu\/colegio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/laorotava.salesianos.edu\/colegio\/wp-json\/wp\/v2\/comments?post=2598"}],"version-history":[{"count":59,"href":"https:\/\/laorotava.salesianos.edu\/colegio\/wp-json\/wp\/v2\/pages\/2598\/revisions"}],"predecessor-version":[{"id":10726,"href":"https:\/\/laorotava.salesianos.edu\/colegio\/wp-json\/wp\/v2\/pages\/2598\/revisions\/10726"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/laorotava.salesianos.edu\/colegio\/wp-json\/wp\/v2\/media\/2655"}],"wp:attachment":[{"href":"https:\/\/laorotava.salesianos.edu\/colegio\/wp-json\/wp\/v2\/media?parent=2598"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}